{"id":849,"date":"2024-02-15T20:19:04","date_gmt":"2024-02-15T19:19:04","guid":{"rendered":"https:\/\/blgastrotrends.de\/?page_id=849"},"modified":"2025-05-02T23:07:03","modified_gmt":"2025-05-02T21:07:03","slug":"ueber-uns","status":"publish","type":"page","link":"https:\/\/exportnavigator.fleischnet.de\/pt\/ueber-uns","title":{"rendered":"Sobre n\u00f3s"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"849\" class=\"elementor elementor-849\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9114edf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9114edf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b02d727\" data-id=\"b02d727\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-92dd716 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92dd716\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-472d3ac\" data-id=\"472d3ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-075a01a elementor-widget elementor-widget-heading\" data-id=\"075a01a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sobre n\u00f3s<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-538f862 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"538f862\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93321f8 elementor-widget elementor-widget-text-editor\" data-id=\"93321f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>A sua b\u00fassola para a engenharia alem\u00e3 num percurso global<\/strong><\/p><p>Num mundo em que a excel\u00eancia tecnol\u00f3gica faz a diferen\u00e7a entre o crescimento e a estagna\u00e7\u00e3o, \u00e9 evidente que <em>exportnavigator.com<\/em> como ponte entre as empresas alem\u00e3s de engenharia mec\u00e2nica e os decisores internacionais. A nossa miss\u00e3o: preparar o caminho para as inova\u00e7\u00f5es \"Made in Germany\" nos mercados globais - de forma eficiente, transparente e em parceria.<\/p><p><strong>O ExportNavigator<\/strong> aproxima fornecedores e utilizadores. Ligamos os fabricantes alem\u00e3es de m\u00e1quinas e sistemas de alta qualidade a empresas de todo o mundo que confiam em tecnologia fi\u00e1vel, solu\u00e7\u00f5es sustent\u00e1veis e sistemas de alto desempenho. Quer se trate de processamento de alimentos ou de embalagens, acompanhamos as tecnologias alem\u00e3s onde quer que sejam necess\u00e1rias.<\/p><p>A nossa plataforma oferece mais do que apenas visibilidade. Proporcionamos contexto, compreens\u00e3o do mercado e pontos de contacto concretos. Com conhecimentos pr\u00e1ticos, estudos de casos, perfis de mercado e uma abordagem de correspond\u00eancia direcionada, n\u00e3o s\u00f3 apoiamos as vendas, como tamb\u00e9m a compreens\u00e3o dos requisitos e oportunidades locais.<\/p><p>Atr\u00e1s <strong>ExportNavigator<\/strong>\u00a0\u00e9 uma equipa de especialistas em tecnologia, exporta\u00e7\u00e3o e comunica\u00e7\u00e3o que falam a l\u00edngua da ind\u00fastria - na Alemanha e no mercado-alvo. N\u00f3s sabemos: O sucesso internacional n\u00e3o \u00e9 uma coincid\u00eancia, mas sim o resultado da confian\u00e7a, da experi\u00eancia cultural e de solu\u00e7\u00f5es personalizadas.<\/p><p><strong>Se quisermos levar o artesanato alem\u00e3o ao mundo, precisamos de um rumo claro.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-108da1a\" data-id=\"108da1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d5d9f0 elementor-widget elementor-widget-heading\" data-id=\"6d5d9f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contactar-nos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ead4e0d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ead4e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2720b0 dce_masking-none elementor-widget elementor-widget-image\" data-id=\"e2720b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg\" class=\"attachment-large size-large wp-image-859\" alt=\"\" srcset=\"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg 1000w, https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian-300x300.jpg 300w, https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian-150x150.jpg 150w, https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian-768x768.jpg 768w, https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian-700x700.jpg 700w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc3af8e elementor-widget elementor-widget-text-editor\" data-id=\"cc3af8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Sebastian Lindner<br \/><\/strong><span data-contrast=\"auto\">Gestor de projectos<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<br \/><\/span><a href=\"tel:+4908937060215\"><span data-contrast=\"auto\">Tel. (089) 370 60-215<\/span><\/a><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<br \/><\/span><a href=\"mailto:s.lindner@blmedien.de\"><span data-contrast=\"auto\">s.lindner@blmedien.de<\/span><span data-ccp-props=\"{&quot;134245417&quot;:false}\">\u00a0<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcber uns Ihr Kompass f\u00fcr deutsche Ingenieurskunst auf globalem Kurs In einer Welt, in der technologische Exzellenz den Unterschied zwischen Wachstum und Stillstand ausmacht, versteht sich exportnavigator.de als Br\u00fccke zwischen [&hellip;]<\/p>","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-849","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcber uns - exportnavigator.fleischnet.de<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcber uns - exportnavigator.fleischnet.de\" \/>\n<meta property=\"og:description\" content=\"\u00dcber uns Ihr Kompass f\u00fcr deutsche Ingenieurskunst auf globalem Kurs In einer Welt, in der technologische Exzellenz den Unterschied zwischen Wachstum und Stillstand ausmacht, versteht sich exportnavigator.de als Br\u00fccke zwischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exportnavigator.fleischnet.de\/pt\/ueber-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"exportnavigator.fleischnet.de\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61556339901555\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T21:07:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns\",\"url\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns\",\"name\":\"\u00dcber uns - exportnavigator.fleischnet.de\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sebastian.jpg\",\"datePublished\":\"2024-02-15T19:19:04+00:00\",\"dateModified\":\"2025-05-02T21:07:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns#primaryimage\",\"url\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sebastian.jpg\",\"contentUrl\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/sebastian.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/ueber-uns#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber uns\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#website\",\"url\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/\",\"name\":\"blgastrotrends.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#organization\",\"name\":\"B&L MedienGesellschaft mbH & Co. KG\",\"url\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/exportnavigator_icon.png\",\"contentUrl\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/exportnavigator_icon.png\",\"width\":500,\"height\":506,\"caption\":\"B&L MedienGesellschaft mbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/exportnavigator.fleischnet.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61556339901555\",\"https:\\\/\\\/www.instagram.com\\\/blgastrotrends.de\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcber uns - exportnavigator.fleischnet.de","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_PT","og_type":"article","og_title":"\u00dcber uns - exportnavigator.fleischnet.de","og_description":"\u00dcber uns Ihr Kompass f\u00fcr deutsche Ingenieurskunst auf globalem Kurs In einer Welt, in der technologische Exzellenz den Unterschied zwischen Wachstum und Stillstand ausmacht, versteht sich exportnavigator.de als Br\u00fccke zwischen [&hellip;]","og_url":"https:\/\/exportnavigator.fleischnet.de\/pt\/ueber-uns\/","og_site_name":"exportnavigator.fleischnet.de","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61556339901555","article_modified_time":"2025-05-02T21:07:03+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns","url":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns","name":"\u00dcber uns - exportnavigator.fleischnet.de","isPartOf":{"@id":"https:\/\/exportnavigator.fleischnet.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns#primaryimage"},"image":{"@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns#primaryimage"},"thumbnailUrl":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg","datePublished":"2024-02-15T19:19:04+00:00","dateModified":"2025-05-02T21:07:03+00:00","breadcrumb":{"@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exportnavigator.fleischnet.de\/ueber-uns"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns#primaryimage","url":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg","contentUrl":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2024\/02\/sebastian.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/exportnavigator.fleischnet.de\/ueber-uns#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/exportnavigator.fleischnet.de\/"},{"@type":"ListItem","position":2,"name":"\u00dcber uns"}]},{"@type":"WebSite","@id":"https:\/\/exportnavigator.fleischnet.de\/#website","url":"https:\/\/exportnavigator.fleischnet.de\/","name":"blgastrotrends.de","description":"","publisher":{"@id":"https:\/\/exportnavigator.fleischnet.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exportnavigator.fleischnet.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/exportnavigator.fleischnet.de\/#organization","name":"B&L MedienGesellschaft mbH & Co. KG","url":"https:\/\/exportnavigator.fleischnet.de\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/exportnavigator.fleischnet.de\/#\/schema\/logo\/image\/","url":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2023\/12\/exportnavigator_icon.png","contentUrl":"https:\/\/exportnavigator.fleischnet.de\/wp-content\/uploads\/2023\/12\/exportnavigator_icon.png","width":500,"height":506,"caption":"B&L MedienGesellschaft mbH & Co. KG"},"image":{"@id":"https:\/\/exportnavigator.fleischnet.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61556339901555","https:\/\/www.instagram.com\/blgastrotrends.de\/"]}]}},"_links":{"self":[{"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/pages\/849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/comments?post=849"}],"version-history":[{"count":20,"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/pages\/849\/revisions"}],"predecessor-version":[{"id":1832,"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/pages\/849\/revisions\/1832"}],"wp:attachment":[{"href":"https:\/\/exportnavigator.fleischnet.de\/pt\/wp-json\/wp\/v2\/media?parent=849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}